{"id":271,"date":"2013-03-22T18:42:10","date_gmt":"2013-03-22T18:42:10","guid":{"rendered":"https:\/\/construction.vamtam.com\/?page_id=271"},"modified":"2013-03-22T18:42:10","modified_gmt":"2013-03-22T18:42:10","slug":"sortable-4-columns","status":"publish","type":"page","link":"https:\/\/evad-services.com\/index.php\/portfolio-layouts\/sortable-4-columns\/","title":{"rendered":"GALLERY STYLE PORTFOLIO"},"content":{"rendered":"<div class=\"limit-wrapper\"><div class=\"row \"><div class=\"wpv-grid grid-1-1  wpv-first-level first unextended no-extended-padding\" style=\"padding-top:0.05px;padding-bottom:0.05px;\" id=\"wpv-column-df5d75869745568647eee5594040d80f\" >\n<section class=\"portfolios isotope normal clearfix title-below has-description \" id=\"6a04826a3d122\">\n\t<nav class=\"sort_by_cat grid-1-1\" data-for=\"#6a04826a3d122\">\n\t<span class=\"inner-wrapper\">\n\t\t<span class=\"cat\"><a data-value=\"all\" href=\"#\" class=\"active\">All<\/a><\/span>\n\t\t\t\t\t\t\t<span class=\"cat\"><a data-value=\"kitchens-bathrooms\" href=\"#\"><span data-text=\"BATHROOMS\">BATHROOMS<\/span><\/a><\/span>\n\t\t\t\t\t<span class=\"cat\"><a data-value=\"general-builder\" href=\"#\"><span data-text=\"BUILDER\">BUILDER<\/span><\/a><\/span>\n\t\t\t\t\t<span class=\"cat\"><a data-value=\"house-extensions\" href=\"#\"><span data-text=\"EXTENSIONS\">EXTENSIONS<\/span><\/a><\/span>\n\t\t\t\t\t<span class=\"cat\"><a data-value=\"gallery\" href=\"#\"><span data-text=\"GALLERY\">GALLERY<\/span><\/a><\/span>\n\t\t\t\t\t<span class=\"cat\"><a data-value=\"html\" href=\"#\"><span data-text=\"HTML\">HTML<\/span><\/a><\/span>\n\t\t\t\t\t<span class=\"cat\"><a data-value=\"image-link\" href=\"#\"><span data-text=\"IMAGE\">IMAGE<\/span><\/a><\/span>\n\t\t\t\t\t<span class=\"cat\"><a data-value=\"portrait\" href=\"#\"><span data-text=\"PORTRAIT\">PORTRAIT<\/span><\/a><\/span>\n\t\t\t\t\t<span class=\"cat\"><a data-value=\"refurbishment\" href=\"#\"><span data-text=\"REFURBISHMENT\">REFURBISHMENT<\/span><\/a><\/span>\n\t\t\t\t\t<span class=\"cat\"><a data-value=\"video\" href=\"#\"><span data-text=\"VIDEO\">VIDEO<\/span><\/a><\/span>\n\t\t\t<\/span>\n<\/nav>\t<ul class=\"clearfix fit-rows portfolio-items\" data-columns=\"3\">\n\t\t<li data-id=\"5327\" data-type=\"video\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:400px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/walking-city\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tWalking City\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"325\" data-type=\"general-builder house-extensions image-link refurbishment\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/my-desk-on-friday\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tMy desk on friday\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"9898\" data-type=\"portrait\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/house-exterior-design\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tHouse exterior design\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"320\" data-type=\"house-extensions\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/working-on-the-new-case\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tWorking on the new case\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"322\" data-type=\"kitchens-bathrooms general-builder house-extensions image-link\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/hello-san-francisco\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tHello San Francisco\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"315\" data-type=\"kitchens-bathrooms image-link\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/our-library-is-great-treasure\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tOur library is great treasure\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"319\" data-type=\"video\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/bicycle-movie\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tThe Rapha Continental: Assynt\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"318\" data-type=\"kitchens-bathrooms refurbishment video\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/how-to-replace-the-airflow-meter\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tHow To Replace The Airflow Meter\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"324\" data-type=\"house-extensions image-link\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/monthly-fun-activities-at-office\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tMonthly Fun Activities at Office!\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"326\" data-type=\"general-builder house-extensions image-link refurbishment\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/meeting-the-needs-of-clients\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tMeeting the Needs of Clients\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"313\" data-type=\"house-extensions video\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/desert-villa\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tDesert Villa\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li><li data-id=\"6215\" data-type=\"house-extensions video\" class=\"has-title has-description grid-1-3 state-closed\">\n\t<div class=\"portfolio-item-wrapper\">\n\t\t\t\t<div class=\"portfolio-image\">\n\t\t\t<div class=\"thumbnail\" style=\"max-height:0px\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"615\" src=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg\" class=\"attachment-theme-large-replacement-loop size-theme-large-replacement-loop wp-post-image\" alt=\"\" srcset=\"https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-800x615.jpg 800w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-555x426.jpg 555w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276.jpg 360w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201.jpg 262w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-360x276@2x.jpg 720w, https:\/\/evad-services.com\/wp-content\/uploads\/2013\/04\/large-262x201@2x.jpg 524w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div><!-- \/ .thumbnail -->\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"portfolio_details\">\n\t\t\t\t<a href=\"https:\/\/evad-services.com\/index.php\/projects\/live-in-treehouses\/\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\tLive in treehouses\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"excerpt\"><p>\u041cirum est notare quam littera gothica, quam nunc.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/li>\t<\/ul>\n\t<\/section>\n<\/div><\/div><\/div>\n<div class=\"push \" style=\"height:70px\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Working from home meant we could vary snack and coffee breaks, change our desks or view, goof off, drink on the job, even spend the day in pajamas, and often meet to gossip or share ideas. On the other hand, we bossed ourselves around, set impossible goals, and demanded longer hours than office jobs usually&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":268,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-271","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/evad-services.com\/index.php\/wp-json\/wp\/v2\/pages\/271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evad-services.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/evad-services.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/evad-services.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/evad-services.com\/index.php\/wp-json\/wp\/v2\/comments?post=271"}],"version-history":[{"count":0,"href":"https:\/\/evad-services.com\/index.php\/wp-json\/wp\/v2\/pages\/271\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/evad-services.com\/index.php\/wp-json\/wp\/v2\/pages\/268"}],"wp:attachment":[{"href":"https:\/\/evad-services.com\/index.php\/wp-json\/wp\/v2\/media?parent=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}